{"id":30425,"date":"2026-02-24T09:58:50","date_gmt":"2026-02-24T14:58:50","guid":{"rendered":"https:\/\/andony.ec\/wordpress\/?post_type=product&#038;p=30425"},"modified":"2026-07-27T10:17:17","modified_gmt":"2026-07-27T15:17:17","slug":"porcion-de-tres-leches-rompope","status":"publish","type":"product","link":"https:\/\/andony.ec\/wordpress\/producto\/porcion-de-tres-leches-rompope\/","title":{"rendered":"Porci\u00f3n De Tres Leches Rompope"},"content":{"rendered":"<p>Bizcocho de vainilla mojada de dulce de tres elches decorada de chantilly, cereza y chispas de chocolate ba\u00f1ado en rompope<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Imagina un pastel tan delicioso que evoca susurros de indulgencia desde el momento en que lo contemplas. La base esponjosa y dorada del bizcocho sirve como lienzo perfecto para el espect\u00e1culo de sabores que est\u00e1 a punto de desplegarse.<\/p>\n","protected":false},"featured_media":30428,"template":"","meta":[],"product_brand":[],"product_cat":[25],"product_tag":[],"class_list":["post-30425","product","type-product","status-publish","has-post-thumbnail","product_cat-postres","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/andony.ec\/wordpress\/wp-json\/wp\/v2\/product\/30425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andony.ec\/wordpress\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/andony.ec\/wordpress\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/andony.ec\/wordpress\/wp-json\/wp\/v2\/media\/30428"}],"wp:attachment":[{"href":"https:\/\/andony.ec\/wordpress\/wp-json\/wp\/v2\/media?parent=30425"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/andony.ec\/wordpress\/wp-json\/wp\/v2\/product_brand?post=30425"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/andony.ec\/wordpress\/wp-json\/wp\/v2\/product_cat?post=30425"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/andony.ec\/wordpress\/wp-json\/wp\/v2\/product_tag?post=30425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}