{"id":369,"date":"2024-04-09T12:51:18","date_gmt":"2024-04-09T17:51:18","guid":{"rendered":"https:\/\/andony.ec\/wordpress\/?post_type=product&#038;p=369"},"modified":"2025-10-22T13:11:38","modified_gmt":"2025-10-22T18:11:38","slug":"torta-de-chocolate","status":"publish","type":"product","link":"https:\/\/andony.ec\/wordpress\/producto\/torta-de-chocolate\/","title":{"rendered":"Torta de Chocolate 1Lb"},"content":{"rendered":"<p>Cake de chocolate con relleno de manjar y cobertura de merengue con chocolate rallado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Imagina un pastel tan delicioso que evoca susurros de indulgencia desde el momento en que lo contemplas. La base esponjosa y dorada del bizcocho sirve como lienzo perfecto para el espect\u00e1culo de sabores que est\u00e1 a punto de desplegarse.<\/p>\n","protected":false},"featured_media":25104,"template":"","meta":[],"product_brand":[],"product_cat":[24],"product_tag":[],"class_list":["post-369","product","type-product","status-publish","has-post-thumbnail","product_cat-tortas","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/andony.ec\/wordpress\/wp-json\/wp\/v2\/product\/369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andony.ec\/wordpress\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/andony.ec\/wordpress\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/andony.ec\/wordpress\/wp-json\/wp\/v2\/media\/25104"}],"wp:attachment":[{"href":"https:\/\/andony.ec\/wordpress\/wp-json\/wp\/v2\/media?parent=369"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/andony.ec\/wordpress\/wp-json\/wp\/v2\/product_brand?post=369"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/andony.ec\/wordpress\/wp-json\/wp\/v2\/product_cat?post=369"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/andony.ec\/wordpress\/wp-json\/wp\/v2\/product_tag?post=369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}