{"id":581,"date":"2024-04-15T10:04:40","date_gmt":"2024-04-15T15:04:40","guid":{"rendered":"https:\/\/andony.ec\/wordpress\/?post_type=product&#038;p=581"},"modified":"2026-03-28T12:42:12","modified_gmt":"2026-03-28T17:42:12","slug":"porcion-rectangular-avellana","status":"publish","type":"product","link":"https:\/\/andony.ec\/wordpress\/producto\/porcion-rectangular-avellana\/","title":{"rendered":"Porcion Rectangular Avellana"},"content":{"rendered":"<p>Porci\u00f3n de cake de chocolate humedecido con alm\u00edbar y relleno de cremoso avellana y man\u00ed acaramelado en el interior.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Imagina un pastel tan delicioso que evoca susurros de indulgencia desde el momento en que lo contemplas. La base esponjosa y dorada del bizcocho sirve como lienzo perfecto para el espect\u00e1culo de sabores que est\u00e1 a punto de desplegarse.<\/p>\n","protected":false},"featured_media":32011,"template":"","meta":[],"product_brand":[],"product_cat":[25],"product_tag":[],"class_list":["post-581","product","type-product","status-publish","has-post-thumbnail","product_cat-postres","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/andony.ec\/wordpress\/wp-json\/wp\/v2\/product\/581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andony.ec\/wordpress\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/andony.ec\/wordpress\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/andony.ec\/wordpress\/wp-json\/wp\/v2\/media\/32011"}],"wp:attachment":[{"href":"https:\/\/andony.ec\/wordpress\/wp-json\/wp\/v2\/media?parent=581"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/andony.ec\/wordpress\/wp-json\/wp\/v2\/product_brand?post=581"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/andony.ec\/wordpress\/wp-json\/wp\/v2\/product_cat?post=581"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/andony.ec\/wordpress\/wp-json\/wp\/v2\/product_tag?post=581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}